{"id":4005,"date":"2021-10-01T15:34:34","date_gmt":"2021-10-01T15:34:34","guid":{"rendered":"https:\/\/www.villapetriolotuscany.com\/?page_id=4005"},"modified":"2025-08-21T16:19:42","modified_gmt":"2025-08-21T16:19:42","slug":"vita-in-liberta","status":"publish","type":"page","link":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/","title":{"rendered":"Vita in Libert\u00e0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4005\" class=\"elementor elementor-4005\" data-elementor-settings=\"{&quot;page_masthead_background_overlay_background&quot;:&quot;gradient&quot;,&quot;page_masthead_background_overlay_color&quot;:&quot;#11111100&quot;,&quot;page_masthead_background_overlay_color_b&quot;:&quot;#111111&quot;,&quot;page_masthead_background_position_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_x_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_x_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_y_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_position_y_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;page_masthead_background_overlay_color_stop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;page_masthead_background_overlay_color_stop_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;page_masthead_background_overlay_color_stop_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;page_masthead_background_overlay_color_b_stop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;page_masthead_background_overlay_color_b_stop_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;page_masthead_background_overlay_color_b_stop_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;page_masthead_background_overlay_gradient_type&quot;:&quot;linear&quot;,&quot;page_masthead_background_overlay_gradient_angle&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:180,&quot;sizes&quot;:[]},&quot;page_masthead_background_overlay_gradient_angle_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;page_masthead_background_overlay_gradient_angle_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d706c32 elementor-section-full_width bg-dark-1 arts-elementor-theme-light elementor-section-height-default elementor-section-height-default\" data-id=\"d706c32\" data-element_type=\"section\" data-settings=\"{&quot;theme_section_color&quot;:&quot;bg-dark-1&quot;,&quot;theme_section_main_theme_text&quot;:&quot;arts-elementor-theme-light&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a8885d7\" data-id=\"a8885d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d557255 text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"d557255\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix   section-fullheight\" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t\t<div class=\"section-fullheight__inner section-fullheight__inner_mobile\">\n\t\t\t\t\t\t<div class=\"section-content__inner container-fluid\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-image section__bg section-content__bg\" data-arts-parallax=true data-arts-parallax-factor=0.1>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-image__wrapper overflow lazy-bg\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" class=\"of-cover\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAQAAAHCGzyUAAAABGdBTUEAALGPC\/xhBQAAADhlWElmTU0AKgAAAAgAAYdpAAQAAAABAAAAGgAAAAAAAqACAAQAAAABAAAAAaADAAQAAAABAAAAAQAAAADa6r\/EAAAAC0lEQVQI12NolQQAASYAn89qhTcAAAAASUVORK5CYII=\" data-id=\"17602\" data-src=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/WildLife1.jpg\" width=\"1920\" height=\"1280\"  data-srcset=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/WildLife1.jpg 1920w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/WildLife1-300x200.jpg 300w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/WildLife1-1024x683.jpg 1024w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/WildLife1-768x512.jpg 768w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/WildLife1-1536x1024.jpg 1536w\"   data-sizes=\"(max-width: 1920px) 100vw, 1920px\"  alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"overlay section-image__overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-scroll-down\">\n\t\t\t\t\t\t<div class=\"circle-button js-circle-button\" data-arts-os-animation=true>\n\t\t<!-- curved label -->\n\t\t<div class=\"circle-button__outer\">\n\t\t\t\t\t\t\t<div class=\"circle-button__wrapper-label\">\n\t\t\t\t\t<div class=\"circle-button__label subheading\">SCORRI<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<!-- - curved label -->\n\t\t<!-- geometry wrapper -->\n\t\t<div class=\"circle-button__inner\">\n\t\t\t<div class=\"circle-button__circle\" data-arts-scroll-down=true data-arts-cursor=\"true\" data-arts-cursor-hide-native=\"true\" data-arts-cursor-scale=\"0\">\n\t\t\t\t<svg class=\"svg-circle\" viewBox=\"0 0 60 60\" width=\"60\" height=\"60\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\">\n\t<circle class=\"circle\" cx=\"30\" cy=\"30\" r=\"29\" fill=\"none\"><\/circle>\n<\/svg>\n\t\t\t<\/div>\n\t\t\t<!-- browsers WITH touch support -->\n\t\t\t<div class=\"circle-button__icon circle-button__icon-touch\">\n\t\t\t\t<svg class=\"svg-arrow-down\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t<path d=\"m32 8c-1.104 0-2 .896-2 2v39.899l-14.552-15.278c-.761-.799-2.026-.832-2.828-.069-.8.762-.831 2.027-.069 2.827l16.62 17.449c.756.756 1.76 1.172 2.829 1.172 1.068 0 2.073-.416 2.862-1.207l16.586-17.414c.762-.8.73-2.065-.069-2.827-.799-.763-2.065-.731-2.827.069l-14.552 15.342v-39.963c0-1.104-.896-2-2-2z\"><\/path>\n<\/svg>\n\t\t\t<\/div>\n\t\t\t<!-- - browsers WITH touch support -->\n\t\t\t<!-- - browsers WITHOUT touch support -->\n\t\t\t<div class=\"circle-button__icon circle-button__icon-mouse\">\n\t\t\t\t<svg class=\"svg-mouse\" width=\"23px\" height=\"35px\" viewBox=\"0 0 23 35\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\">\n\t<!-- border -->\n\t<path class=\"svg-mouse__border\" d=\"M11.5,0 C5.15875132,0 0,5.23135343 0,11.6610111 L0,23.3396542 C0,29.7691456 5.15875132,35 11.5,35 C17.8412487,35 23,29.7693119 23,23.3396542 L23,11.6610111 C23,5.23135343 17.8410847,0 11.5,0 Z M21.7222404,23.3396542 C21.7222404,29.0545544 17.136538,33.7037222 11.5,33.7037222 C5.86346203,33.7037222 1.27775956,29.0545544 1.27775956,23.3396542 L1.27775956,11.6610111 C1.27775956,5.946111 5.86346203,1.29627781 11.5,1.29627781 C17.136538,1.29627781 21.7222404,5.94594466 21.7222404,11.6610111 L21.7222404,23.3396542 Z\"><\/path>\n\t<!-- - border -->\n\t<!-- wheel -->\n\t<path class=\"svg-mouse__wheel\" d=\"M11.5,4 C11.2238902,4 11,4.28321727 11,4.63321727 L11,10.3667827 C11,10.7167827 11.2238902,11 11.5,11 C11.7761098,11 12,10.7167827 12,10.3667827 L12,4.63321727 C11.9998717,4.28321727 11.7761098,4 11.5,4 Z\"><\/path>\n\t<!-- - wheel -->\n<\/svg>\n\t\t\t<\/div>\n\t\t\t<!-- - browsers WITHOUT touch support -->\n\t\t<\/div>\n\t\t<!-- - geometry wrapper -->\n\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a0c0814 elementor-section-full_width pt-small pb-xsmall elementor-section-height-default elementor-section-height-default\" data-id=\"1a0c0814\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-306f843f\" data-id=\"306f843f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-687ceb82 text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"687ceb82\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h2>Vita in Libert\u00e0<\/h2><h4>Esperienze<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section__headline mt-1 mt-md-2\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f80aa3 elementor-hidden-desktop elementor-widget elementor-widget-text-editor\" data-id=\"7f80aa3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Villa Petriolo offre una riconnessione con la natura senza perdere il lusso e comfort offrendo ai suoi visitatori l&#8217;esperienza della Toscana nella sua essenza pi\u00f9 antica. Scopri tutte le esperienze nella fattoria fra animali, vigne e olivete all&#8217;interno della nostra tenuta. Scopri anche la nostra Policy ed Info relative ai prezzi e prenotazioni delle esperienze.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b6e10b elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"8b6e10b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Villa Petriolo offre una riconnessione con la natura senza perdere il lusso<br \/>e comfort offrendo ai suoi visitatori l&#8217;esperienza della Toscana nella sua essenza pi\u00f9 antica.<br \/>Scopri tutte le esperienze nella fattoria fra animali, vigne e olivete all&#8217;interno della nostra tenuta.<br \/>Scopri anche la nostra Policy ed Info relative ai prezzi e prenotazioni delle esperienze.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a33d3a3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3a33d3a3\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ed52b09\" data-id=\"1ed52b09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c1b565d elementor-widget elementor-widget-rhye-widget-parallax-background\" data-id=\"4c1b565d\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-parallax-background.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section section-image section text-center\" data-arts-parallax=true data-arts-parallax-factor=0.1 data-arts-os-animation=true>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-image__wrapper overflow mask-reveal lazy-bg\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-1\">\n\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"of-cover\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAQAAAHCGzyUAAAABGdBTUEAALGPC\/xhBQAAADhlWElmTU0AKgAAAAgAAYdpAAQAAAABAAAAGgAAAAAAAqACAAQAAAABAAAAAaADAAQAAAABAAAAAQAAAADa6r\/EAAAAC0lEQVQI12NolQQAASYAn89qhTcAAAAASUVORK5CYII=\" data-id=\"15726\" data-src=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/06\/Horse-Riding.jpg\" width=\"1920\" height=\"1280\"  data-srcset=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/06\/Horse-Riding.jpg 1920w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/06\/Horse-Riding-300x200.jpg 300w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/06\/Horse-Riding-1024x683.jpg 1024w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/06\/Horse-Riding-768x512.jpg 768w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/06\/Horse-Riding-1536x1024.jpg 1536w\"   data-sizes=\"(max-width: 1920px) 100vw, 1920px\"  alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53371d5a elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"53371d5a\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-72636fd3 pt-medium pb-medium container-fluid bg-white\" data-id=\"72636fd3\" data-element_type=\"column\" data-settings=\"{&quot;theme_section_color&quot;:&quot;bg-white&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b700e04 elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"4b700e04\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h3>Avventura in E-Bike<\/h3><h4>vita in libert\u00e0<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section__headline mt-1 mt-md-2\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1c4500 elementor-widget elementor-widget-text-editor\" data-id=\"d1c4500\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tParti per una nuova avventura in bici elettrica insieme ad una Guida esperta e ai tuoi amici. Strade, campagne, paesi e tramonti; un viaggio su due ruote che assumer\u00e0 un colore tutto nuovo!\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2514b01 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"2514b01\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.villapetriolotuscany.com\/it\/portfolio\/avventura-in-e-bike\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SCOPRI<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-77702a62\" data-id=\"77702a62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dfcb98f elementor-widget elementor-widget-rhye-widget-parallax-background\" data-id=\"1dfcb98f\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-parallax-background.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section section-image section text-center\" data-arts-os-animation=true>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-image__wrapper mask-reveal lazy-bg\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-1\">\n\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"of-cover\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAQAAAHCGzyUAAAABGdBTUEAALGPC\/xhBQAAADhlWElmTU0AKgAAAAgAAYdpAAQAAAABAAAAGgAAAAAAAqACAAQAAAABAAAAAaADAAQAAAABAAAAAQAAAADa6r\/EAAAAC0lEQVQI12NolQQAASYAn89qhTcAAAAASUVORK5CYII=\" data-id=\"13290\" data-src=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/12\/20221008_150627.jpg\" width=\"1280\" height=\"1920\"  data-srcset=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/12\/20221008_150627.jpg 1280w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/12\/20221008_150627-200x300.jpg 200w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/12\/20221008_150627-683x1024.jpg 683w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/12\/20221008_150627-768x1152.jpg 768w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/12\/20221008_150627-1024x1536.jpg 1024w\"   data-sizes=\"(max-width: 1280px) 100vw, 1280px\"  alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61f0f67b elementor-section-full_width elementor-section-content-middle elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"61f0f67b\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45c6367d\" data-id=\"45c6367d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6973a4e1 elementor-widget elementor-widget-rhye-widget-parallax-background\" data-id=\"6973a4e1\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-parallax-background.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section section-image section text-center\" data-arts-os-animation=true>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-image__wrapper mask-reveal lazy-bg\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-1\">\n\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"of-cover\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAQAAAHCGzyUAAAABGdBTUEAALGPC\/xhBQAAADhlWElmTU0AKgAAAAgAAYdpAAQAAAABAAAAGgAAAAAAAqACAAQAAAABAAAAAaADAAQAAAABAAAAAQAAAADa6r\/EAAAAC0lEQVQI12NolQQAASYAn89qhTcAAAAASUVORK5CYII=\" data-id=\"10216\" data-src=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg\" width=\"1280\" height=\"1920\"  data-srcset=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg 1280w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748-200x300.jpg 200w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748-683x1024.jpg 683w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748-768x1152.jpg 768w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748-1024x1536.jpg 1024w\"   data-sizes=\"(max-width: 1280px) 100vw, 1280px\"  alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40725198 pt-medium pb-medium container-fluid bg-white\" data-id=\"40725198\" data-element_type=\"column\" data-settings=\"{&quot;theme_section_color&quot;:&quot;bg-white&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-776891b elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"776891b\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h3>Cavalcando nella Pittoresca Toscana<\/h3><h4>Vita in Libert\u00e0<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section__headline mt-1 mt-md-2\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72999bd elementor-widget elementor-widget-text-editor\" data-id=\"72999bd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Due meravigliose ore in sella per assaporare la magia e lo stupore delle colline Toscane, con una prospettiva privilegiata rispetto a chi resta a terra. Un&#8217;esperienza intima da vivere in gruppi di due o quattro persone alla scoperta del territorio e dei meravigliosi cavalli.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f633a87 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"f633a87\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.villapetriolotuscany.com\/it\/portfolio\/cavalcando-nella-pittoresca-toscana\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SCOPRI<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e4a439 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"8e4a439\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7488e7b pt-medium pb-medium container-fluid bg-white\" data-id=\"7488e7b\" data-element_type=\"column\" data-settings=\"{&quot;theme_section_color&quot;:&quot;bg-white&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5aea86 elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"b5aea86\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h3>Esperienza in Elicottero<\/h3><h4>vita in libert\u00e0<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section__headline mt-1 mt-md-2\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e8ec4e elementor-widget elementor-widget-text-editor\" data-id=\"9e8ec4e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sorvolare la Toscana in Elicottero \u00e8 un&#8217;esperienza inimitabile, ricca di adrenalina. Vivi insieme ad un Pilota Esperto l\u2019opportunit\u00e0 unica di osservare dall\u2019alto i panorami pi\u00f9 belli e i luoghi pi\u00f9 meravigliosi del nostro territorio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b178c17 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"b178c17\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.villapetriolotuscany.com\/it\/portfolio\/esperienza-elicottero\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SCOPRI<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aa0ab78\" data-id=\"aa0ab78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5821f1 elementor-widget elementor-widget-rhye-widget-parallax-background\" data-id=\"b5821f1\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-parallax-background.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section section-image section text-center\" data-arts-os-animation=true>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-image__wrapper mask-reveal lazy-bg\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-1\">\n\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"of-cover\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAQAAAHCGzyUAAAABGdBTUEAALGPC\/xhBQAAADhlWElmTU0AKgAAAAgAAYdpAAQAAAABAAAAGgAAAAAAAqACAAQAAAABAAAAAaADAAQAAAABAAAAAQAAAADa6r\/EAAAAC0lEQVQI12NolQQAASYAn89qhTcAAAAASUVORK5CYII=\" data-id=\"13323\" data-src=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/01\/pexels-tanhauser-vazquez-r-11687748.jpg\" width=\"1280\" height=\"1920\"  data-srcset=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/01\/pexels-tanhauser-vazquez-r-11687748.jpg 1280w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/01\/pexels-tanhauser-vazquez-r-11687748-200x300.jpg 200w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/01\/pexels-tanhauser-vazquez-r-11687748-683x1024.jpg 683w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/01\/pexels-tanhauser-vazquez-r-11687748-768x1152.jpg 768w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2023\/01\/pexels-tanhauser-vazquez-r-11687748-1024x1536.jpg 1024w\"   data-sizes=\"(max-width: 1280px) 100vw, 1280px\"  alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5dfd85 pt-medium pb-medium elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5dfd85\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd73f03\" data-id=\"cd73f03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24c179fc text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"24c179fc\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section__headline mb-1 mb-md-2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f239849 elementor-widget elementor-widget-text-editor\" data-id=\"f239849\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Troverai pi\u00f9 nei boschi che nei libri. Alberi e pietre ti insegneranno ci\u00f2 che non si pu\u00f2 imparare dai maestri.<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e1483d elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"5e1483d\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-be74542 pt-medium pb-medium container-fluid bg-white\" data-id=\"be74542\" data-element_type=\"column\" data-settings=\"{&quot;theme_section_color&quot;:&quot;bg-white&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7331aae elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"7331aae\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h3>Caccia al Tartufo<\/h3><h4>vita in libert\u00e0<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section__headline mt-1 mt-md-2\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9c3d68 elementor-widget elementor-widget-text-editor\" data-id=\"a9c3d68\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;opportunit\u00e0 giusta per scoprire il &#8220;tesoro&#8221; nascosto fra i boschi toscani e conoscere il metodo di addestramento dei cani da tartufo. <span class=\"S1PPyQ\">Dopo la caccia, l&#8217;Osteria di Golpaja vi delizier\u00e0 con la sua cucina e piatti deliziosi a base di tartufo, conquistando anche i palati pi\u00f9 sofisticati.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62e2091 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"62e2091\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.villapetriolotuscany.com\/it\/portfolio\/cacciaaltartufo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SCOPRI<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7afcd6b\" data-id=\"7afcd6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2955020 elementor-widget elementor-widget-rhye-widget-parallax-background\" data-id=\"2955020\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-parallax-background.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section section-image section text-center\" data-arts-os-animation=true>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-image__wrapper mask-reveal lazy-bg\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-1\">\n\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"of-cover\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAQAAAHCGzyUAAAABGdBTUEAALGPC\/xhBQAAADhlWElmTU0AKgAAAAgAAYdpAAQAAAABAAAAGgAAAAAAAqACAAQAAAABAAAAAaADAAQAAAABAAAAAQAAAADa6r\/EAAAAC0lEQVQI12NolQQAASYAn89qhTcAAAAASUVORK5CYII=\" data-id=\"17610\" data-src=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/Progetto-senza-titolo5_1-1.jpg\" width=\"1280\" height=\"1920\"  data-srcset=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/Progetto-senza-titolo5_1-1.jpg 1280w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/Progetto-senza-titolo5_1-1-200x300.jpg 200w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/Progetto-senza-titolo5_1-1-683x1024.jpg 683w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/Progetto-senza-titolo5_1-1-768x1152.jpg 768w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/07\/Progetto-senza-titolo5_1-1-1024x1536.jpg 1024w\"   data-sizes=\"(max-width: 1280px) 100vw, 1280px\"  alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cea4dd elementor-section-full_width elementor-section-content-middle elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"5cea4dd\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-841ced7\" data-id=\"841ced7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6920416 elementor-widget elementor-widget-rhye-widget-parallax-background\" data-id=\"6920416\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-parallax-background.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section section-image section text-center\" data-arts-os-animation=true>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-image__wrapper mask-reveal lazy-bg\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-1\">\n\t\t\t\t\t\t<div class=\"mask-reveal__layer mask-reveal__layer-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"of-cover\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAQAAAHCGzyUAAAABGdBTUEAALGPC\/xhBQAAADhlWElmTU0AKgAAAAgAAYdpAAQAAAABAAAAGgAAAAAAAqACAAQAAAABAAAAAaADAAQAAAABAAAAAQAAAADa6r\/EAAAAC0lEQVQI12NolQQAASYAn89qhTcAAAAASUVORK5CYII=\" data-id=\"18886\" data-src=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2025\/04\/Padel_00-1.webp\" width=\"900\" height=\"1200\"  data-srcset=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2025\/04\/Padel_00-1.webp 900w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2025\/04\/Padel_00-1-225x300.webp 225w, https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2025\/04\/Padel_00-1-768x1024.webp 768w\"   data-sizes=\"(max-width: 900px) 100vw, 900px\"  alt=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f2f8a23 pt-medium pb-medium container-fluid bg-white\" data-id=\"f2f8a23\" data-element_type=\"column\" data-settings=\"{&quot;theme_section_color&quot;:&quot;bg-white&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8ae6cc elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"f8ae6cc\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h3>Padel Experience<\/h3>\n<h4>Vita in libert\u00e0<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section__headline mt-1 mt-md-2\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c002479 elementor-widget elementor-widget-text-editor\" data-id=\"c002479\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vivi un&#8217;esperienza unica tra sport, natura e relax con il padel nel cuore delle colline toscane, grazie alla nostra partnership con il Centro Padel San Miniato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-496a3ce elementor-align-left elementor-widget elementor-widget-button\" data-id=\"496a3ce\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.villapetriolotuscany.com\/it\/portfolio\/padel-experience\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SCOPRI<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dfa48a7 pt-medium pb-medium elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6dfa48a7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24ff804a\" data-id=\"24ff804a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73070c86 text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"73070c86\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section__headline mb-1 mb-md-2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h3><span class=\"italiano\">Informazioni generali<\/span><\/h3><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6609d9b elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6609d9b\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1f5dcea9\" data-id=\"1f5dcea9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53d9684 text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"53d9684\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text mb-1\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h4>PRENOTAZIONI<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t<div class=\"section-content__text split-text js-split-text\" data-split-text-type=\"lines\" data-split-text-set=\"lines\"><p><small>La prenotazione di qualsiasi delle nostre esperienze deve essere consultata prima con la Reception la quale confermer\u00e0 il servizio in caso di disponibilit\u00e0. Consigliamo fortemente di prenotare in anticipo in modo da assicurare la propria prenotazione a tempo. Confermiamo sempre le nostre esperienze con un minimo di 2 persone e un massimo di 8 persone, salvo esclusione per le esperienze in E-bike, a Cavallo e in Elicottero come annotato nella brochure. Le nostre esperienze sono strutturate per piccoli gruppi fra ospiti dell'hotel e ospiti giornalieri che possono condividere la stessa esperienza prenotata. Il massimo di ospiti \u00e8 di 8 persone. In caso di esperienze private dovete consultare la Reception che vi mander\u00e0 un preventivo personalizzato. In caso di gruppi superiori alle 8 persone l'esperienza diventa privata.<\/small><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c804617\" data-id=\"c804617\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1527b2 text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"b1527b2\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text mb-1\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h4>Politiche riguardo agli eventi climatici<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t<div class=\"section-content__text split-text js-split-text\" data-split-text-type=\"lines\" data-split-text-set=\"lines\"><p><small>Villa Petriolo offre molte esperienze che si svolgono parzialmente o totalmente all'esterno della struttura. In caso di eventi climatici che rendono impossibile l'esecuzione della parte esterna dell'esperienza, determinate attivit\u00e0 saranno eseguite solo in parte all'interno della struttura alla stessa tariffa. Le esperienze che non possono essere eseguite nemmeno parzialmente all'interno saranno posposte quando possibile o saranno cancellate senza penalit\u00e0. Villa Petriolo non \u00e8 responsabile per gli eventi climatici, ad ogni modo resta a disposizione dei clienti per trovare una soluzione ad eventuali inconvenienti causati da quest'ultimi.<\/small><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-376ab0c\" data-id=\"376ab0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1008d48d text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"1008d48d\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text mb-1\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h4>Ritardi, No Show e Cancellazione<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t<div class=\"section-content__text split-text js-split-text\" data-split-text-type=\"lines\" data-split-text-set=\"lines\"><p><small>I clienti devono arrivare 5 minuti prima dell'inizio dell'esperienza senza importare che esperienza sia. In caso di ritardo, i clienti non potranno pi\u00f9 partecipare all'esperienze. In caso di ritardo o No Show, Villa Petriolo ha il diritto di addebitare il totale del servizio. I clienti che prenotano direttamente con noi avranno la possibilit\u00e0 di addebitare il servizio in camera; tutti gli altri casi dovranno pagare in anticipo il servizio (la settimana prima del servizio). Il servizio in Elicottero deve essere pagato in anticipo per essere confermato anche se ospiti dell'hotel. La nostra politica di cancellazione senza penalit\u00e0 \u00e8 di 7 giorni prima della data in cui l'esperienza \u00e8 confermata.<\/small><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a90d449 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a90d449\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3fece5c0\" data-id=\"3fece5c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64f6d27 text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"64f6d27\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text mb-1\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h4>Prezzi Bambini<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t<div class=\"section-content__text split-text js-split-text\" data-split-text-type=\"lines\" data-split-text-set=\"lines\"><p><small>Dagli 0 ai 3 anni: gratuito. Dai 4 anni ai 12 anni: 50% dell'esperienza. Eccetto per le esperienze in E-Bike, a Cavallo e l'Elicottero che sono da consultare con la Reception.<\/small><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3d9fc56\" data-id=\"3d9fc56\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65ab4b09 text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"65ab4b09\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text mb-1\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h4>Programma settimanale e orari<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t<div class=\"section-content__text split-text js-split-text\" data-split-text-type=\"lines\" data-split-text-set=\"lines\"><p><small>Le nostre attivit\u00e0 si svolgono dal Lunedi al Sabato eccetto per le Classi di Cucina che sono dal Lunedi al Venerd\u00ec solo al mattino. La Domenica le nostre attivit\u00e0 non sono prenotabili eccetto per le esperienze in E-bike, a Cavallo e l'Elicottero che sono operate da associazioni locali.<\/small><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-16ca8ad3\" data-id=\"16ca8ad3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ae21894 text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"5ae21894\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text mb-1\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h4>INFORMAZIONE IMPORTANTE<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t<div class=\"section-content__text split-text js-split-text\" data-split-text-type=\"lines\" data-split-text-set=\"lines\"><p><small>I clienti devono informare la reception al momento della conferma della prenotazione in caso di restrizione alimentare, allergie, intolleranze o diete specifiche.<\/small><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-27563c9 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27563c9\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-09be3e6\" data-id=\"09be3e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-856e90a text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"856e90a\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text mb-1\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h4>Listino Prezzi<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t<div class=\"section-content__text split-text js-split-text\" data-split-text-type=\"lines\" data-split-text-set=\"lines\"><p><small>I nostri prezzi potrebbero cambiare durante l'arco dell'anno se Villa Petriolo lo ritiene necessario.<\/small><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ec0ca8d elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec0ca8d\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b245e5a\" data-id=\"b245e5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5094ac elementor-widget elementor-widget-text-editor\" data-id=\"e5094ac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>prenotazioni<\/h4>\n<small>La prenotazione di qualsiasi delle nostre esperienze deve essere consultata prima con la Reception la quale confermer\u00e0 il servizio in caso di disponibilit\u00e0. Consigliamo fortemente di prenotare in anticipo in modo da assicurare la propria prenotazione a tempo. Confermiamo sempre le nostre esperienze con un minimo di 2 persone e un massimo di 8 persone, salvo esclusione per le esperienze in E-bike, a Cavallo e in Elicottero come annotato nella brochure. Le nostre esperienze sono strutturate per piccoli gruppi fra ospiti dell&#8217;hotel e ospiti giornalieri che possono condividere la stessa esperienza prenotata. Il massimo di ospiti \u00e8 di 8 persone. In caso di esperienze private dovete consultare la Reception che vi mander\u00e0 un preventivo personalizzato. In caso di gruppi superiori alle 8 persone l&#8217;esperienza diventa privata.<\/small>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3b75915 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b75915\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-33ee1e8\" data-id=\"33ee1e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98a500a elementor-widget elementor-widget-text-editor\" data-id=\"98a500a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>politiche riguardo a eventi climatici<\/h4><p><small><small>Villa Petriolo offre molte esperienze che si svolgono parzialmente o totalmente all&#8217;esterno della struttura. In caso di eventi climatici che rendono impossibile l&#8217;esecuzione della parte esterna dell&#8217;esperienza, determinate attivit\u00e0 saranno eseguite solo in parte all&#8217;interno della struttura alla stessa tariffa. Le esperienze che non possono essere eseguite nemmeno parzialmente all&#8217;interno saranno posposte quando possibile o saranno cancellate senza penalit\u00e0. Villa Petriolo non \u00e8 responsabile per gli eventi climatici, ad ogni modo resta a disposizione dei clienti per trovare una soluzione ad eventuali inconvenienti causati da quest&#8217;ultimi.<\/small><\/small><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7516c7e elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7516c7e\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-11cc284\" data-id=\"11cc284\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d47d659 elementor-widget elementor-widget-text-editor\" data-id=\"d47d659\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>ritardi, no show e cancellazioni<\/h4>\n<small>I clienti devono arrivare 5 minuti prima dell&#8217;inizio dell&#8217;esperienza senza importare che esperienza sia. In caso di ritardo, i clienti non potranno pi\u00f9 partecipare all&#8217;esperienze. In caso di ritardo o No Show, Villa Petriolo ha il diritto di addebitare il totale del servizio. I clienti che prenotano direttamente con noi avranno la possibilit\u00e0 di addebitare il servizio in camera; tutti gli altri casi dovranno pagare in anticipo il servizio (la settimana prima del servizio). Il servizio in Elicottero deve essere pagato in anticipo per essere confermato anche se ospiti dell&#8217;hotel. La nostra politica di cancellazione senza penalit\u00e0 \u00e8 di 7 giorni prima della data in cui l&#8217;esperienza \u00e8 confermata.<\/small>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cb3a18e elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"cb3a18e\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8ffcc53\" data-id=\"8ffcc53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-389a999 elementor-widget elementor-widget-text-editor\" data-id=\"389a999\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>prezzi bambini<\/h4><p><small>Dagli 0 ai 3 anni: gratuito. Dai 4 anni ai 12 anni: 50% dell&#8217;esperienza. Eccetto per le esperienze in E-Bike, a Cavallo e l&#8217;Elicottero che sono da consultare con la Reception.<\/small><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-10652e6 elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"10652e6\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-198a2f0\" data-id=\"198a2f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d593248 elementor-widget elementor-widget-text-editor\" data-id=\"d593248\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>programma settimanale e orari<\/h4><p><small>Le nostre attivit\u00e0 si svolgono dal Lunedi al Sabato eccetto per le Classi di Cucina che sono dal Lunedi al Venerd\u00ec solo al mattino. La Domenica le nostre attivit\u00e0 non sono prenotabili eccetto per le esperienze in E-bike, a Cavallo, e l&#8217;Elicottero che sono operate da associazioni locali.<\/small><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ff23655 elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"ff23655\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e89c9e6\" data-id=\"e89c9e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f15009 elementor-widget elementor-widget-text-editor\" data-id=\"6f15009\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>informazione importante<\/h4><p><small>I clienti devono informare la reception al momento della conferma della prenotazione in caso di restrizione alimentare, allergie, intolleranze o diete specifiche.<\/small><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1dc9551 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1dc9551\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9ce15dc\" data-id=\"9ce15dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa568a3 text-center elementor-widget elementor-widget-rhye-widget-content-block\" data-id=\"fa568a3\" data-element_type=\"widget\" data-widget_type=\"rhye-widget-content-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"section section-content clearfix  \" data-arts-os-animation=\"true\">\n\t\t\t\t\t\t<div class=\"section-content__inner\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__heading split-text js-split-text mb-1\" data-split-text-type=\"lines,words\" data-split-text-set=\"words\"><h4>Listino Prezzi<\/h4><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content__wrapper-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"w-100\"><\/div>\n\t\t\t\t\t\t\t<div class=\"section-content__text split-text js-split-text\" data-split-text-type=\"lines\" data-split-text-set=\"lines\"><p><small>I nostri prezzi potrebbero cambiare durante l'arco dell'anno se Villa Petriolo lo ritiene necessario.<\/small><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SCORRI Vita in Libert\u00e0 Esperienze Villa Petriolo offre una riconnessione con la natura senza perdere il lusso e comfort offrendo ai suoi visitatori l&#8217;esperienza della Toscana nella sua essenza pi\u00f9 antica. Scopri tutte le esperienze nella fattoria fra animali, vigne e olivete all&#8217;interno della nostra tenuta. Scopri anche la nostra Policy ed Info relative ai [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10216,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4005","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Scopri la Vita in Libert\u00e0 di Villa Petriolo vicino Firenze<\/title>\n<meta name=\"description\" content=\"Scopri una riconnessione con la natura attraverso le esperienze nella fattoria fra animali, vigne e olivete all\u2019interno della nostra tenuta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scopri la Vita in Libert\u00e0 di Villa Petriolo vicino Firenze\" \/>\n<meta property=\"og:description\" content=\"Scopri una riconnessione con la natura attraverso le esperienze nella fattoria fra animali, vigne e olivete all\u2019interno della nostra tenuta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/\" \/>\n<meta property=\"og:site_name\" content=\"Villa Petriolo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-21T16:19:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/\",\"url\":\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/\",\"name\":\"Scopri la Vita in Libert\u00e0 di Villa Petriolo vicino Firenze\",\"isPartOf\":{\"@id\":\"https:\/\/www.villapetriolotuscany.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg\",\"datePublished\":\"2021-10-01T15:34:34+00:00\",\"dateModified\":\"2025-08-21T16:19:42+00:00\",\"description\":\"Scopri una riconnessione con la natura attraverso le esperienze nella fattoria fra animali, vigne e olivete all\u2019interno della nostra tenuta.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#primaryimage\",\"url\":\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg\",\"contentUrl\":\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg\",\"width\":1280,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.villapetriolotuscany.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vita in Libert\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.villapetriolotuscany.com\/#website\",\"url\":\"https:\/\/www.villapetriolotuscany.com\/\",\"name\":\"Villa Petriolo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.villapetriolotuscany.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.villapetriolotuscany.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.villapetriolotuscany.com\/#organization\",\"name\":\"Villa Petriolo\",\"url\":\"https:\/\/www.villapetriolotuscany.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.villapetriolotuscany.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/01\/LOGO-VP_UNIVERSAL-Marrone.png\",\"contentUrl\":\"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/01\/LOGO-VP_UNIVERSAL-Marrone.png\",\"width\":277,\"height\":340,\"caption\":\"Villa Petriolo\"},\"image\":{\"@id\":\"https:\/\/www.villapetriolotuscany.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scopri la Vita in Libert\u00e0 di Villa Petriolo vicino Firenze","description":"Scopri una riconnessione con la natura attraverso le esperienze nella fattoria fra animali, vigne e olivete all\u2019interno della nostra tenuta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/","og_locale":"it_IT","og_type":"article","og_title":"Scopri la Vita in Libert\u00e0 di Villa Petriolo vicino Firenze","og_description":"Scopri una riconnessione con la natura attraverso le esperienze nella fattoria fra animali, vigne e olivete all\u2019interno della nostra tenuta.","og_url":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/","og_site_name":"Villa Petriolo","article_modified_time":"2025-08-21T16:19:42+00:00","og_image":[{"width":1280,"height":1920,"url":"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/","url":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/","name":"Scopri la Vita in Libert\u00e0 di Villa Petriolo vicino Firenze","isPartOf":{"@id":"https:\/\/www.villapetriolotuscany.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#primaryimage"},"image":{"@id":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg","datePublished":"2021-10-01T15:34:34+00:00","dateModified":"2025-08-21T16:19:42+00:00","description":"Scopri una riconnessione con la natura attraverso le esperienze nella fattoria fra animali, vigne e olivete all\u2019interno della nostra tenuta.","breadcrumb":{"@id":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#primaryimage","url":"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg","contentUrl":"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2022\/03\/DSC09748.jpg","width":1280,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.villapetriolotuscany.com\/it\/vita-in-liberta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.villapetriolotuscany.com\/it\/"},{"@type":"ListItem","position":2,"name":"Vita in Libert\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.villapetriolotuscany.com\/#website","url":"https:\/\/www.villapetriolotuscany.com\/","name":"Villa Petriolo","description":"","publisher":{"@id":"https:\/\/www.villapetriolotuscany.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.villapetriolotuscany.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.villapetriolotuscany.com\/#organization","name":"Villa Petriolo","url":"https:\/\/www.villapetriolotuscany.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.villapetriolotuscany.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/01\/LOGO-VP_UNIVERSAL-Marrone.png","contentUrl":"https:\/\/www.villapetriolotuscany.com\/wp-content\/uploads\/2024\/01\/LOGO-VP_UNIVERSAL-Marrone.png","width":277,"height":340,"caption":"Villa Petriolo"},"image":{"@id":"https:\/\/www.villapetriolotuscany.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.villapetriolotuscany.com\/it\/wp-json\/wp\/v2\/pages\/4005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.villapetriolotuscany.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.villapetriolotuscany.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.villapetriolotuscany.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.villapetriolotuscany.com\/it\/wp-json\/wp\/v2\/comments?post=4005"}],"version-history":[{"count":6,"href":"https:\/\/www.villapetriolotuscany.com\/it\/wp-json\/wp\/v2\/pages\/4005\/revisions"}],"predecessor-version":[{"id":19172,"href":"https:\/\/www.villapetriolotuscany.com\/it\/wp-json\/wp\/v2\/pages\/4005\/revisions\/19172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.villapetriolotuscany.com\/it\/wp-json\/wp\/v2\/media\/10216"}],"wp:attachment":[{"href":"https:\/\/www.villapetriolotuscany.com\/it\/wp-json\/wp\/v2\/media?parent=4005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}